{"id":70,"count":1,"description":"","link":"http:\/\/nicolewillson.com\/blog\/tag\/2020-election\/","name":"2020 Election","slug":"2020-election","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/nicolewillson.com\/blog\/wp-json\/wp\/v2\/tags\/70"}],"collection":[{"href":"http:\/\/nicolewillson.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/nicolewillson.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/nicolewillson.com\/blog\/wp-json\/wp\/v2\/posts?tags=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}